{"id":24495,"date":"2022-06-30T12:29:06","date_gmt":"2022-06-30T12:29:06","guid":{"rendered":"https:\/\/sigma.bike\/devoluciones-de-la-tienda-web-de-sigma\/"},"modified":"2022-06-30T12:29:07","modified_gmt":"2022-06-30T12:29:07","slug":"devoluciones-de-la-tienda-web-de-sigma","status":"publish","type":"page","link":"https:\/\/sigma.bike\/es\/centro-de-servicios\/pedido-en-la-tienda-web-de-sigma\/devoluciones-de-la-tienda-web-de-sigma\/","title":{"rendered":"Devoluciones de la tienda web de SIGMA"},"content":{"rendered":"\n<section class=\"wp-block-custom-container alignwide block-content  block-content--spacing-top block-content--spacing-bottom return-guest\"><style>.block-content--spacing-top{padding-top:3.5rem}@media (min-width: 768px){.block-content--spacing-top{padding-top:8rem}}.block-content--spacing-bottom{padding-bottom:3.5rem}@media (min-width: 768px){.block-content--spacing-bottom{padding-bottom:8rem}}.block-content--margin-top{margin-top:4.8rem}@media (min-width: 768px){.block-content--margin-top{margin-top:8rem}}.block-content--margin-bottom{margin-bottom:4.8rem}@media (min-width: 768px){.block-content--margin-bottom{margin-bottom:8rem}}\n<\/style><div class=\"container container--wide\"><div class=\"container__body\">\n<h2 class=\"wp-block-heading\">Directrices para las devoluciones<\/h2>\n\n\n\n<div class=\"wp-block-custom-columns columns-row row\"><style>.columns-row--spacing-top{padding-top:3.5rem}@media (min-width: 768px){.columns-row--spacing-top{padding-top:8rem}}.columns-row--spacing-bottom{padding-bottom:3.5rem}@media (min-width: 768px){.columns-row--spacing-bottom{padding-bottom:8rem}}.columns-row--margin-top{margin-top:4.8rem}@media (min-width: 768px){.columns-row--margin-top{margin-top:8rem}}.columns-row--margin-bottom{margin-bottom:4.8rem}@media (min-width: 768px){.columns-row--margin-bottom{margin-bottom:8rem}}\n<\/style>\n<div class=\"wp-block-custom-column col col-12 col-xl-6\">\n<p>Si no est\u00e1s satisfecho con el producto que nos has comprado, puedes devolverlo en un plazo de veinti\u00fan (21) d\u00edas naturales.<\/p>\n\n\n\n<p><strong>Los art\u00edculos deben ser devueltos a nuestro Centro de Devoluciones sin haber sido utilizados y en condici\u00f3n de nuevos. Debe incluirse una copia del albar\u00e1n de entrega.<\/strong> <\/p>\n\n\n\n<p>El precio de compra y los posibles impuestos se reembolsar\u00e1n al m\u00e9todo de pago utilizado para comprar el producto.<\/p>\n\n\n\n<p>Los gastos de env\u00edo s\u00f3lo se reembolsar\u00e1n si el art\u00edculo se devuelve debido a un defecto o da\u00f1o. Si deseas devolver un art\u00edculo porque est\u00e1 da\u00f1ado o defectuoso, consulta la secci\u00f3n &#8220;Producto da\u00f1ado o defectuoso&#8221; que aparece a continuaci\u00f3n.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n<\/div>\n\n\n<div class=\"wp-block-custom-column col col-12 col-xl-6\"><\/div>\r\n<\/div>\n\n\n\n<div class=\"wp-block-custom-columns columns-row row\">\n<div class=\"wp-block-custom-column col col-12 col-xl-6\">\n<h2 class=\"wp-block-heading\">Instrucciones de devoluci\u00f3n<\/h2>\n\n\n\n<p>Por favor, sigue las siguientes instrucciones para embalar y devolver el producto. S\u00f3lo si se siguen exactamente las instrucciones podremos procesar la devoluci\u00f3n con \u00e9xito.<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\"><li>Rellena este formulario con tu n\u00famero de pedido y tu direcci\u00f3n de correo electr\u00f3nico <\/li><li>Recibir\u00e1s un correo electr\u00f3nico de nuestra parte y podr\u00e1s iniciar tu devoluci\u00f3n. Abre el enlace en tu correo electr\u00f3nico.<\/li><li>Ahora puedes seleccionar los productos que deseas devolver. Una vez hecho esto, recibir\u00e1s una etiqueta de DHL.<\/li><li>Devuelve el art\u00edculo en su embalaje original.<\/li><li>Empaqueta el art\u00edculo con cuidado para que no se da\u00f1e durante el env\u00edo.<\/li><li>Adjunta una copia del albar\u00e1n de entrega. No podemos tramitar las devoluciones de los env\u00edos recibidos sin albar\u00e1n.<\/li><li>Tras la comprobaci\u00f3n, te devolveremos el dinero. (Ten en cuenta que los gastos de env\u00edo no se reembolsar\u00e1n).<\/li><\/ol><\/div>\n\n\n\n<div class=\"wp-block-custom-column col col-12 col-xl-5 offset-xl-1\"><p><div class=\"woocommerce\"><\/div><\/p>\n\n\n<p><form class=\"woocommerce-form woocommerce-form-return-request return-request\" method=\"post\" >\n\t\n\t\n\t<p class=\"form-row form-row-first\">\n\t\t<label for=\"return-request-email\">Order email&nbsp;<span class=\"required\">*<\/span><\/label>\n\t\t<input type=\"text\" class=\"input-text\" name=\"email\" id=\"return-request-email\" autocomplete=\"email\" \/>\n\t<\/p>\n\n\t<p class=\"form-row form-row-last\">\n\t\t<label for=\"return-request-order-id\">Order id&nbsp;<span class=\"required\">*<\/span><\/label>\n\t\t<input type=\"text\" class=\"input-text\" name=\"order_id\" id=\"return-request-order-id\" autocomplete=\"off\" \/>\n\t<\/p>\n\n\t<div class=\"clear\"><\/div>\n\n\t\n\t<p class=\"form-row\">\n\t\t<input type=\"hidden\" id=\"woocommerce-stc-return-request-nonce\" name=\"woocommerce-stc-return-request-nonce\" value=\"2e2c8fb51a\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/24495\" \/>\t\t<button type=\"submit\" class=\"woocommerce-button button woocommerce-form-return_request__submit\" name=\"return_request\" value=\"Submit\">Submit<\/button>\n\t<\/p>\n\n\t<div class=\"clear\"><\/div>\n\n\t\n<\/form>\n<\/p>\n<\/div>\n<\/div>\n<\/div><\/div><\/section>\n<style>.wp-block-image{margin-bottom:0}@media screen and (min-width: 993px){body:not(.wp-admin) .wp-block-image.editorskit-no-desktop{display:none}}@media screen and (min-width: 600px) and (max-width: 992px){body:not(.wp-admin) .wp-block-image.editorskit-no-tablet{display:none}}@media screen and (max-width: 599px){body:not(.wp-admin) .wp-block-image.editorskit-no-mobile{display:none}}@media screen and (max-width: 768px) and (min-width: 737px){body:not(.wp-admin) .blockopts-hide.blockopts-tablet,body:not(.wp-admin) .editorskit-no-tablet{display:inherit}}@media screen and (max-width: 736px){body:not(.wp-admin) .blockopts-hide.blockopts-mobile,body:not(.wp-admin) .editorskit-no-mobile{display:inherit}}@media screen and (min-width: 769px){body:not(.wp-admin) .blockopts-hide.blockopts-desktop,body:not(.wp-admin) .editorskit-no-desktop{display:inherit}}\n<\/style>\n<figure class=\"wp-block-image alignfull size-full\"><img decoding=\"async\" src=\"https:\/\/sigma.bike\/wp-content\/uploads\/2022\/06\/sigma-originals-bc-5-0-header-02.jpg\" alt=\"\" class=\"wp-image-24175\"\/><\/figure>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":21276,"parent":24507,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-24495","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/sigma.bike\/es\/wp-json\/wp\/v2\/pages\/24495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sigma.bike\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sigma.bike\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sigma.bike\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sigma.bike\/es\/wp-json\/wp\/v2\/comments?post=24495"}],"version-history":[{"count":0,"href":"https:\/\/sigma.bike\/es\/wp-json\/wp\/v2\/pages\/24495\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/sigma.bike\/es\/wp-json\/wp\/v2\/pages\/24507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sigma.bike\/es\/wp-json\/wp\/v2\/media\/21276"}],"wp:attachment":[{"href":"https:\/\/sigma.bike\/es\/wp-json\/wp\/v2\/media?parent=24495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}